{"id":12557,"date":"2015-09-04T16:40:15","date_gmt":"2015-09-04T14:40:15","guid":{"rendered":"http:\/\/www.lauroikastola.eus\/once-alumnos-y-alumnas-cursaran-un-trimestre-en-canada-2\/"},"modified":"2015-09-07T09:37:20","modified_gmt":"2015-09-07T07:37:20","slug":"once-alumnos-y-alumnas-cursaran-un-trimestre-en-canada","status":"publish","type":"post","link":"https:\/\/www.lauroikastola.eus\/es\/once-alumnos-y-alumnas-cursaran-un-trimestre-en-canada\/","title":{"rendered":"Once alumnos y alumnas cursar\u00e1n un trimestre en Canad\u00e1"},"content":{"rendered":"<p>El 28 de agosto, once alumnos y alumnas de 3\u00ba y 4\u00ba de la ESO viajaron a Canad\u00e1 para cursar all\u00ed el primer trimestre del curso 15\/16.<\/p>\n<p>Esta nueva iniciativa, enmarcada dentro del plan de Internacionalizaci\u00f3n de la Ikastola, consiste en la inmersi\u00f3n en familia y centro educativo en el estado de Nueva Escocia desde septiembre a noviembre.<\/p>\n<p><a href=\"http:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2015\/09\/IMG_5661.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12555 size-large\" src=\"http:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2015\/09\/IMG_5661-1024x768.jpg\" alt=\"IMG_5661\" width=\"940\" height=\"705\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 28 de agosto, once alumnos y alumnas de 3\u00ba y 4\u00ba de la ESO viajaron a Canad\u00e1 para cursar all\u00ed el primer trimestre del curso 15\/16. Esta nueva iniciativa, enmarcada dentro del plan de Internacionalizaci\u00f3n de la Ikastola, consiste en la inmersi\u00f3n en familia y centro educativo en el estado de Nueva Escocia desde &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[],"class_list":["post-12557","post","type-post","status-publish","format-standard","hentry","category-lauro-gaur"],"_links":{"self":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/12557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=12557"}],"version-history":[{"count":0,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/12557\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=12557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/categories?post=12557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/tags?post=12557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}