{"id":12576,"date":"2015-09-07T11:04:41","date_gmt":"2015-09-07T09:04:41","guid":{"rendered":"http:\/\/www.lauroikastola.eus\/betabot-taldeak-gaurko-finalean-parte-hartuko-du-2\/"},"modified":"2015-11-02T11:48:15","modified_gmt":"2015-11-02T10:48:15","slug":"betabot-taldeak-gaurko-finalean-parte-hartuko-du","status":"publish","type":"post","link":"https:\/\/www.lauroikastola.eus\/es\/betabot-taldeak-gaurko-finalean-parte-hartuko-du\/","title":{"rendered":"El equipo Betabot participa en la final del concurso MOONBOTS"},"content":{"rendered":"<p>El grupo <strong>BETABOT<\/strong> integrado\u00a0 Ander Aguiriano, Jon Andoni Bret\u00f3n, Sue Gonz\u00e1lez y Asier Rementer\u00eda, de 1\u00ba de bachiller, participan el 7 de septiembre en la final del concurso lanzado a nivel mundial por Google, en junio, titulado <a href=\"http:\/\/www.moonbots.org\/\"><strong>MOONBOTS<\/strong><\/a>.\u00a0 Este concurso consiste en\u00a0 desarrollar y construir un robot a escala y con LEGO, que simule diferentes misiones en la Luna. El equipo trabaja con la colaboraci\u00f3n de la profesora Amaia P\u00e9rez y el profesor Borja del R\u00edo.<\/p>\n<p>De los 233 equipos presentaron, se han clasificado para la final tan s\u00f3lo 30, entre los que se encuentra el equipo de Lauro Ikastola. Competir\u00e1 el lunes, 7 de septiembre, junto con 17 equipos de Estados Unidos, 3 de Israel, 2 de Brasil y otros como Estonia, Malasia, M\u00e9xico, Italia, India, Tailandia y Rumania.<\/p>\n<p>El premio principal\u00a0 es un viaje para todo el equipo a Jap\u00f3n, donde tendr\u00edan la oportunidad de conocer a los cient\u00edficos que est\u00e1n participando en el concurso XPRIZE que Google lanz\u00f3 hace ya 8 a\u00f1os a ingenier\u00edas y empresas de rob\u00f3tica.<\/p>\n<p>Uno de los requisitos exigidos por Google era la divulgaci\u00f3n del proyecto en su entorno, y para ello el Ayuntamiento de Getxo y la Comisi\u00f3n de Fiestas del Puerto Viejo de Algorta \u00a0les instal\u00f3 una carpa durante una ma\u00f1ana donde pudieron presentarlo al numeroso p\u00fablico que se acerc\u00f3.<\/p>\n<p>El pasado 31 de Agosto hicieron la presentaci\u00f3n de su web <a href=\"http:\/\/www.betabot-moonbot.co.nr\">www.betabot-moonbot.co.nr<\/a> .\u00a0 Euskadi Irratia les entrevist\u00f3 en directo y la EITB realiz\u00f3 el reportaje que pod\u00e9is ver en el siguiente enlace: <a href=\"http:\/\/www.eitb.eus\/es\/noticias\/sociedad\/videos\/detalle\/3415766\/video-los-alumnos-lauro-muestran-su-simulacion-mision-lunar\/\">pincha aqu\u00ed<\/a>.<\/p>\n<p><strong>ZORTE ON!!!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grupo BETABOT integrado\u00a0 Ander Aguiriano, Jon Andoni Bret\u00f3n, Sue Gonz\u00e1lez y Asier Rementer\u00eda, de 1\u00ba de bachiller, participan el 7 de septiembre en la final del concurso lanzado a nivel mundial por Google, en junio, titulado MOONBOTS.\u00a0 Este concurso consiste en\u00a0 desarrollar y construir un robot a escala y con LEGO, que simule diferentes &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[],"class_list":["post-12576","post","type-post","status-publish","format-standard","hentry","category-lauro-gaur"],"_links":{"self":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/12576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=12576"}],"version-history":[{"count":0,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/12576\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=12576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/categories?post=12576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/tags?post=12576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}