{"id":126684,"date":"2024-01-25T13:02:40","date_gmt":"2024-01-25T12:02:40","guid":{"rendered":"https:\/\/www.lauroikastola.eus\/hide-dohino-japoniar-euskalduna-ikastolan-izan-da-bere-ikasketa-prozesua-azaltzen\/"},"modified":"2024-01-25T16:43:22","modified_gmt":"2024-01-25T15:43:22","slug":"hide-dohino-japoniar-euskalduna-ikastolan-izan-da-bere-ikasketa-prozesua-azaltzen","status":"publish","type":"post","link":"https:\/\/www.lauroikastola.eus\/es\/hide-dohino-japoniar-euskalduna-ikastolan-izan-da-bere-ikasketa-prozesua-azaltzen\/","title":{"rendered":"Hide Dohino, japon\u00e9s euskaldun, nos ha explicado su proceso de aprendizaje del euskara"},"content":{"rendered":"<p>El historiador japon\u00e9s Hide Dohino (Yokohama, 1994) ha aprendido euskara en solo dos a\u00f1os. Ha acudido a la Ikastola invitado por el seminario de Euskara para reunirse con el alumnado de 1\u00ba de Bachiller y explicarles c\u00f3mo est\u00e1 siendo su proceso de aprendizaje: de una forma muy pr\u00e1ctica, relacion\u00e1ndose con la gente, aprendiendo tambi\u00e9n de sus costumbres, aunque tambi\u00e9n ha trabajado la gram\u00e1tica y lee mucho: \u00abHe creado mi propia escuela, y funciona: trabajar jugando.\u00bb.<\/p><p>Opina que es algo natural \u00abaprender la lengua del pa\u00eds al que viajas\u00bb.<\/p><p>Le impulsa un gran inter\u00e9s por aprender, y tambi\u00e9n ha estudio otras lenguas del entorno; incluso dialectos o acentos de dichas lenguas.<\/p><p>\u00a1Ha terminado la sesi\u00f3n con un <em>bertso<\/em>!!<\/p><p><em>Harigato <\/em>Hido! Nos has ense\u00f1ado que hay diferentes formas de ser <em>euskaldun<\/em>.<\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Hide Dohino historialari japoniarra, bertsotan Lauro Ikastolan.\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/h1zE0Kg3plM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure><figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_3-scaled.jpg\"><img decoding=\"async\" data-id=\"126671\" src=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_3-1024x768.jpg\" alt=\"\" class=\"wp-image-126671\"\/><\/a><\/figure><\/figure><figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_1-scaled.jpg\"><img decoding=\"async\" data-id=\"126674\" src=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_1-763x1024.jpg\" alt=\"\" class=\"wp-image-126674\"\/><\/a><\/figure>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_2-scaled.jpg\"><img decoding=\"async\" data-id=\"126676\" src=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_2-760x1024.jpg\" alt=\"\" class=\"wp-image-126676\"\/><\/a><\/figure>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_4-scaled.jpg\"><img decoding=\"async\" data-id=\"126679\" src=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2024\/01\/Hide_Lauro_4-768x1024.jpg\" alt=\"\" class=\"wp-image-126679\"\/><\/a><\/figure><\/figure>","protected":false},"excerpt":{"rendered":"<p>El historiador japon\u00e9s Hide Dohino (Yokohama, 1994) ha aprendido euskara en solo dos a\u00f1os. Ha acudido a la Ikastola invitado por el seminario de Euskara para reunirse con el alumnado de 1\u00ba de Bachiller y explicarles c\u00f3mo est\u00e1 siendo su proceso de aprendizaje: de una forma muy pr\u00e1ctica, relacion\u00e1ndose con la gente, aprendiendo tambi\u00e9n de &#8230;<\/p>\n","protected":false},"author":1,"featured_media":126670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[],"class_list":["post-126684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lauro-gaur"],"_links":{"self":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/126684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=126684"}],"version-history":[{"count":0,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/126684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media\/126670"}],"wp:attachment":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=126684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/categories?post=126684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/tags?post=126684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}