{"id":150506,"date":"2026-03-26T12:04:32","date_gmt":"2026-03-26T11:04:32","guid":{"rendered":"https:\/\/www.lauroikastola.eus\/euskara-gara\/"},"modified":"2026-03-27T09:04:25","modified_gmt":"2026-03-27T08:04:25","slug":"euskara-gara","status":"publish","type":"post","link":"https:\/\/www.lauroikastola.eus\/es\/euskara-gara\/","title":{"rendered":"Euskara gara!"},"content":{"rendered":"<p>\u00a1Korrika Txikia ederra Lauron! Todos los alumnos y alumnas, de etapa en etapa, han participado en la Korrika de la Ikastola, llevando el testigo y el mensaje que nos une en torno al euskera.<\/p><p>Una vez finalizado el recorrido, nos hemos reunido en el patio para leer el mensaje, disfrutar de las actuaciones y la m\u00fasica, y homenajear a los participantes en <a href=\"https:\/\/www.laurofundazioa.eus\/berbalagun-ekimena\/\">BERBALAGUNA <\/a>que llevar\u00e1n el testigo en el kil\u00f3metro de la Ikastola en Bilbao.<\/p><p>\u00a1Ya hemos calentado motores para el domingo!<strong> <a href=\"https:\/\/www.lauroikastola.eus\/es\/martxoaren-19an-hasiko-da-24-korrika-euskara-gara\/\">\u00a1Ven al kilometro de la Ikastola!<\/a>!<\/strong><\/p><p><strong>GORA KORRIKA!<\/strong><\/p><figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Korrika 24 Txikia Lauro Ikastolan\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/feTf6RpGczc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure><div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2026\/03\/Korrika-Txikia-Mezua.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de Korrika Txikia - Mezua.\"><\/object><a id=\"wp-block-file--media-3db0840c-e420-431c-8147-6f47d950cce8\" href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2026\/03\/Korrika-Txikia-Mezua.pdf\">Korrika Txikia &#8211; Mezua<\/a><a href=\"https:\/\/www.lauroikastola.eus\/wp-content\/uploads\/2026\/03\/Korrika-Txikia-Mezua.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-3db0840c-e420-431c-8147-6f47d950cce8\">Descarga<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00a1Korrika Txikia ederra Lauron! Todos los alumnos y alumnas, de etapa en etapa, han participado en la Korrika de la Ikastola, llevando el testigo y el mensaje que nos une en torno al euskera. Una vez finalizado el recorrido, nos hemos reunido en el patio para leer el mensaje, disfrutar de las actuaciones y la &#8230;<\/p>\n","protected":false},"author":1,"featured_media":150505,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[116],"tags":[],"class_list":["post-150506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lauro-gaur"],"_links":{"self":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/150506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/comments?post=150506"}],"version-history":[{"count":6,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/150506\/revisions"}],"predecessor-version":[{"id":150518,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/posts\/150506\/revisions\/150518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media\/150505"}],"wp:attachment":[{"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/media?parent=150506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/categories?post=150506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lauroikastola.eus\/es\/wp-json\/wp\/v2\/tags?post=150506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}